{"id":11,"date":"2024-03-25T13:40:05","date_gmt":"2024-03-25T16:40:05","guid":{"rendered":"https:\/\/coreia.online\/?p=11"},"modified":"2024-03-25T13:40:05","modified_gmt":"2024-03-25T16:40:05","slug":"a-industria-de-entretenimento-da-coreia-do-sul","status":"publish","type":"post","link":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/","title":{"rendered":"A ind\u00fastria de entretenimento da Coreia do Sul"},"content":{"rendered":"<div class=\"flex-1 overflow-hidden\">\n<div class=\"react-scroll-to-bottom--css-tcccb-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-tcccb-1n7m0yu\">\n<div class=\"flex flex-col text-sm pb-9\">\n<div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-3\">\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\n<div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\">\n<div class=\"relative flex w-full flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"fe29eaa0-3b3b-4d0f-93ed-2dc9a51eed20\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">A ind\u00fastria de entretenimento da <a href=\"https:\/\/catracalivre.com.br\/arquivo\/cinco-razoes-para-visitar-e-amar-seul-capital-da-coreia-do-sul\/\">Coreia do Sul<\/a> \u00e9 uma pot\u00eancia global em constante crescimento e expans\u00e3o.\u00a0 Entre os principais ramos culturais coreanos destacam-se:<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>1. M\u00fasica Pop (K-pop):<\/strong> <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">O K-pop \u00e9 o produto cultural mais conhecido, pois, grupos como BTS, BLACKPINK, EXO e TWICE atraem milh\u00f5es de f\u00e3s em todo o mundo.<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>2. Dramas de Televis\u00e3o (K-dramas):<\/strong> <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Os K-dramas ganharam popularidade internacional nos \u00faltimos anos, como: &#8220;Boys Over Flowers&#8221; e &#8220;Descendants of the Sun&#8221;, pois, possuem hist\u00f3rias envolventes, produ\u00e7\u00f5es de alta qualidade.<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>3. Filmes:<\/strong><\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"> A ind\u00fastria cinematogr\u00e1fica\u00a0 tamb\u00e9m ganhou destaque internacional, com filmes aclamados pela cr\u00edtica como &#8220;Parasita&#8221;, dirigido por Bong Joon-ho, ganhando pr\u00eamios em importantes, incluindo o Oscar.<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>4. Jogos e Entretenimento Digital:<\/strong> <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">A Coreia tamb\u00e9m \u00e9 uma l\u00edder global na ind\u00fastria de jogos, pois, possui\u00a0 equipes sul-coreanas dominando competi\u00e7\u00f5es internacionais em jogos como League of Legends, StarCraft II e Overwatch.<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>5. Moda e Beleza:<\/strong> <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">A Coreia do Sul tamb\u00e9m influencia as tend\u00eancias globais de moda e beleza enfatizando a pele clara e saud\u00e1vel e popularizando produtos como cremes BB, m\u00e1scaras faciais e cosm\u00e9ticos inovadores em todo o mundo.<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>6. Turismo Cultural:<\/strong> <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">A cultura pop sul-coreana tamb\u00e9m impulsionou o turismo cultural, com f\u00e3s viajando para a Coreia do Sul para experimentar os locais de filmagem de seus dramas e filmes favoritos, al\u00e9m de participar de concertos de K-pop.<\/span><\/p>\n<\/div>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Cr\u00edtica<\/strong>: <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><span style=\"font-size: 16px;\">Embora a ind\u00fastria de entretenimento da Coreia do Sul tenha alcan\u00e7ado um sucesso not\u00e1vel em escala global, tamb\u00e9m enfrenta cr\u00edticas em v\u00e1rias \u00e1reas, por exemplo:<\/span><\/span><\/p>\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\">Padr\u00f5es de Trabalho e Bem-Estar dos Artistas:<\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Os padr\u00f5es de trabalho exigentes afetam o bem-estar dos artistas, pois, h\u00e1 relatos de longas horas de trabalho, pr\u00e1ticas rigorosas de treinamento e falta de tempo livre.<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\">Controle Excessivo das Ag\u00eancias: <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">As ag\u00eancias de entretenimento s\u00e3o frequentemente criticadas por seu controle excessivo sobre a vida pessoal e profissional dos artistas porque limitam a liberdade criativa dos artistas contribuindo para problemas de sa\u00fade mental.<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\">Padr\u00f5es de Beleza Irrealistas: <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">A ind\u00fastria sul-coreana de entretenimento \u00e9 conhecida por promover padr\u00f5es de beleza irreais. Isso pode criar press\u00e3o sobre os artistas e tamb\u00e9m influenciar negativamente a autoimagem e a confian\u00e7a dos jovens f\u00e3s.<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\">Falta de Diversidade Representativa: <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Apesar do sucesso global do K-pop e dos K-dramas a ind\u00fastria sul-coreana de entretenimento ainda carece de diversidade representativa, tanto em termos de etnia quanto de g\u00eanero.<\/span><\/p>\n<h1><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Conclus\u00e3o:<\/strong> <\/span><\/h1>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">A\u00a0 ind\u00fastria de entretenimento da Coreia do Sul continua a prosperar e influenciar a cultura global de maneiras significativas com seu K-pop cativante, dramas de televis\u00e3o envolventes, filmes aclamados pela cr\u00edtica e vibrante cena de jogos e eSports. <\/span><span style=\"font-family: arial, helvetica, sans-serif;\">Todavia, enquanto a ind\u00fastria de entretenimento da Coreia do Sul desfruta de um sucesso consider\u00e1vel, \u00e9 importante reconhecer e abordar as quest\u00f5es e cr\u00edticas que enfrenta, visando garantir um ambiente de trabalho saud\u00e1vel e inclusivo, promovendo a diversidade e incentivando a criatividade e a originalidade.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-1 flex justify-start gap-3 empty:hidden\">\n<div class=\"text-gray-400 flex self-end lg:self-center items-center justify-center lg:justify-start mt-0 -ml-1 h-7 gap-[2px] visible\">\n<p>&nbsp;<\/p>\n<div class=\"flex items-center gap-1.5 text-xs\"><\/div>\n<div class=\"flex\"><\/div>\n<\/div>\n<\/div>\n<div class=\"pr-2 lg:pr-0\"><\/div>\n<\/div>\n<div class=\"absolute\">\n<div class=\"flex w-full gap-2 items-center justify-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"w-full pt-2 md:pt-0 dark:border-white\/20 md:border-transparent md:dark:border-transparent md:w-[calc(100%-.5rem)]\">\n<form class=\"stretch mx-2 flex flex-row gap-3 last:mb-2 md:mx-4 md:last:mb-6 lg:mx-auto lg:max-w-2xl xl:max-w-3xl\">\n<div class=\"relative flex h-full flex-1 flex-col\">\n<div class=\"absolute bottom-full left-0 right-0\"><\/div>\n<div class=\"flex w-full items-center\">\n<div class=\"overflow-hidden [&amp;:has(textarea:focus)]:border-token-border-xheavy [&amp;:has(textarea:focus)]:shadow-[0_2px_6px_rgba(0,0,0,.05)] flex flex-col w-full flex-grow relative border dark:text-white rounded-2xl bg-token-main-surface-primary border-token-border-medium\"><\/div>\n<\/div>\n<\/div>\n<\/form>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A ind\u00fastria de entretenimento da Coreia do Sul \u00e9 uma pot\u00eancia global em constante crescimento e expans\u00e3o.\u00a0 Entre os principais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A ind\u00fastria de entretenimento da Coreia do Sul - Coreia Online<\/title>\n<meta name=\"description\" content=\"A ind\u00fastria de entretenimento da Coreia do Sul \u00e9 uma pot\u00eancia global em constante crescimento e expans\u00e3o.\u00a0 Entre os principais ramos ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A ind\u00fastria de entretenimento da Coreia do Sul - Coreia Online\" \/>\n<meta property=\"og:description\" content=\"A ind\u00fastria de entretenimento da Coreia do Sul \u00e9 uma pot\u00eancia global em constante crescimento e expans\u00e3o.\u00a0 Entre os principais ramos ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/\" \/>\n<meta property=\"og:site_name\" content=\"Coreia Online\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-25T16:40:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coreia.online\/wp-content\/uploads\/2024\/03\/seul.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"599\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CoreiaOnline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CoreiaOnline\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/\",\"url\":\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/\",\"name\":\"A ind\u00fastria de entretenimento da Coreia do Sul - Coreia Online\",\"isPartOf\":{\"@id\":\"https:\/\/coreia.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/coreia.online\/wp-content\/uploads\/2024\/03\/seul.jpg\",\"datePublished\":\"2024-03-25T16:40:05+00:00\",\"dateModified\":\"2024-03-25T16:40:05+00:00\",\"author\":{\"@id\":\"https:\/\/coreia.online\/#\/schema\/person\/e2a67941d3a9d3a3d5c7666f7020a884\"},\"description\":\"A ind\u00fastria de entretenimento da Coreia do Sul \u00e9 uma pot\u00eancia global em constante crescimento e expans\u00e3o.\u00a0 Entre os principais ramos ...\",\"breadcrumb\":{\"@id\":\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#primaryimage\",\"url\":\"https:\/\/coreia.online\/wp-content\/uploads\/2024\/03\/seul.jpg\",\"contentUrl\":\"https:\/\/coreia.online\/wp-content\/uploads\/2024\/03\/seul.jpg\",\"width\":599,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/coreia.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A ind\u00fastria de entretenimento da Coreia do Sul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/coreia.online\/#website\",\"url\":\"https:\/\/coreia.online\/\",\"name\":\"Coreia Online\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/coreia.online\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/coreia.online\/#\/schema\/person\/e2a67941d3a9d3a3d5c7666f7020a884\",\"name\":\"CoreiaOnline\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/coreia.online\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=96&d=mm&r=g\",\"caption\":\"CoreiaOnline\"},\"sameAs\":[\"https:\/\/coreia.online\"],\"url\":\"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A ind\u00fastria de entretenimento da Coreia do Sul - Coreia Online","description":"A ind\u00fastria de entretenimento da Coreia do Sul \u00e9 uma pot\u00eancia global em constante crescimento e expans\u00e3o.\u00a0 Entre os principais ramos ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/","og_locale":"en_US","og_type":"article","og_title":"A ind\u00fastria de entretenimento da Coreia do Sul - Coreia Online","og_description":"A ind\u00fastria de entretenimento da Coreia do Sul \u00e9 uma pot\u00eancia global em constante crescimento e expans\u00e3o.\u00a0 Entre os principais ramos ...","og_url":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/","og_site_name":"Coreia Online","article_published_time":"2024-03-25T16:40:05+00:00","og_image":[{"width":599,"height":900,"url":"https:\/\/coreia.online\/wp-content\/uploads\/2024\/03\/seul.jpg","type":"image\/jpeg"}],"author":"CoreiaOnline","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CoreiaOnline","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/","url":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/","name":"A ind\u00fastria de entretenimento da Coreia do Sul - Coreia Online","isPartOf":{"@id":"https:\/\/coreia.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#primaryimage"},"image":{"@id":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/coreia.online\/wp-content\/uploads\/2024\/03\/seul.jpg","datePublished":"2024-03-25T16:40:05+00:00","dateModified":"2024-03-25T16:40:05+00:00","author":{"@id":"https:\/\/coreia.online\/#\/schema\/person\/e2a67941d3a9d3a3d5c7666f7020a884"},"description":"A ind\u00fastria de entretenimento da Coreia do Sul \u00e9 uma pot\u00eancia global em constante crescimento e expans\u00e3o.\u00a0 Entre os principais ramos ...","breadcrumb":{"@id":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#primaryimage","url":"https:\/\/coreia.online\/wp-content\/uploads\/2024\/03\/seul.jpg","contentUrl":"https:\/\/coreia.online\/wp-content\/uploads\/2024\/03\/seul.jpg","width":599,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/coreia.online\/index.php\/2024\/03\/25\/a-industria-de-entretenimento-da-coreia-do-sul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/coreia.online\/"},{"@type":"ListItem","position":2,"name":"A ind\u00fastria de entretenimento da Coreia do Sul"}]},{"@type":"WebSite","@id":"https:\/\/coreia.online\/#website","url":"https:\/\/coreia.online\/","name":"Coreia Online","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coreia.online\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/coreia.online\/#\/schema\/person\/e2a67941d3a9d3a3d5c7666f7020a884","name":"CoreiaOnline","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/coreia.online\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=96&d=mm&r=g","caption":"CoreiaOnline"},"sameAs":["https:\/\/coreia.online"],"url":"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/"}]}},"_links":{"self":[{"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/posts\/11"}],"collection":[{"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":2,"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/posts\/11\/revisions"}],"predecessor-version":[{"id":16,"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/posts\/11\/revisions\/16"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/media\/15"}],"wp:attachment":[{"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/categories?post=11"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/tags?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}