{"id":1,"name":"CoreiaOnline","url":"https:\/\/coreia.online","description":"","link":"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/","slug":"coreiaonline","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CoreiaOnline, Autor em Coreia Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"CoreiaOnline, Autor em Coreia Online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/\" \/>\n<meta property=\"og:site_name\" content=\"Coreia Online\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/\",\"url\":\"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/\",\"name\":\"CoreiaOnline, Autor em Coreia Online\",\"isPartOf\":{\"@id\":\"https:\/\/coreia.online\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/coreia.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arquivos para CoreiaOnline\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/coreia.online\/#website\",\"url\":\"https:\/\/coreia.online\/\",\"name\":\"Coreia Online\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/coreia.online\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/coreia.online\/#\/schema\/person\/e2a67941d3a9d3a3d5c7666f7020a884\",\"name\":\"CoreiaOnline\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/coreia.online\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=96&d=mm&r=g\",\"caption\":\"CoreiaOnline\"},\"sameAs\":[\"https:\/\/coreia.online\"],\"mainEntityOfPage\":{\"@id\":\"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CoreiaOnline, Autor em Coreia Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/","og_locale":"en_US","og_type":"profile","og_title":"CoreiaOnline, Autor em Coreia Online","og_url":"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/","og_site_name":"Coreia Online","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=500&d=mm&r=g"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/","url":"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/","name":"CoreiaOnline, Autor em Coreia Online","isPartOf":{"@id":"https:\/\/coreia.online\/#website"},"breadcrumb":{"@id":"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coreia.online\/index.php\/author\/coreiaonline\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/coreia.online\/"},{"@type":"ListItem","position":2,"name":"Arquivos para CoreiaOnline"}]},{"@type":"WebSite","@id":"https:\/\/coreia.online\/#website","url":"https:\/\/coreia.online\/","name":"Coreia Online","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coreia.online\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/coreia.online\/#\/schema\/person\/e2a67941d3a9d3a3d5c7666f7020a884","name":"CoreiaOnline","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/coreia.online\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/594b767d018ac4e866c1affcd9038f08?s=96&d=mm&r=g","caption":"CoreiaOnline"},"sameAs":["https:\/\/coreia.online"],"mainEntityOfPage":{"@id":"https:\/\/coreia.online\/index.php\/author\/coreiaonline\/"}}]}},"_links":{"self":[{"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/users\/1"}],"collection":[{"href":"https:\/\/coreia.online\/index.php\/wp-json\/wp\/v2\/users"}]}}